{"id":16735,"date":"2025-05-15T20:57:55","date_gmt":"2025-05-15T20:57:55","guid":{"rendered":"https:\/\/italchamber.qc.ca\/speakers\/federico-roncarolo-canada-excellence-research-chair-cerc-one-urban-health\/"},"modified":"2025-05-15T20:58:06","modified_gmt":"2025-05-15T20:58:06","slug":"federico-roncarolo-canada-excellence-research-chair-cerc-one-urban-health","status":"publish","type":"speaker","link":"https:\/\/italchamber.qc.ca\/it\/speakers\/federico-roncarolo-canada-excellence-research-chair-cerc-one-urban-health\/","title":{"rendered":"Federico Roncarolo \u2013 Canada Excellence Research Chair (CERC) One Urban Health"},"content":{"rendered":"","protected":false},"featured_media":16731,"template":"","country":[],"class_list":["post-16735","speaker","type-speaker","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Federico Roncarolo \u2013 Canada Excellence Research Chair (CERC) One Urban Health - ICCC<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/italchamber.qc.ca\/it\/speakers\/federico-roncarolo-canada-excellence-research-chair-cerc-one-urban-health\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Federico Roncarolo \u2013 Canada Excellence Research Chair (CERC) One Urban Health - ICCC\" \/>\n<meta property=\"og:url\" content=\"https:\/\/italchamber.qc.ca\/it\/speakers\/federico-roncarolo-canada-excellence-research-chair-cerc-one-urban-health\/\" \/>\n<meta property=\"og:site_name\" content=\"ICCC\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-15T20:58:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/italchamber.qc.ca\/wp-content\/uploads\/2025\/05\/Untitled-design.png\" \/>\n\t<meta property=\"og:image:width\" content=\"350\" \/>\n\t<meta property=\"og:image:height\" content=\"350\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/italchamber.qc.ca\\\/it\\\/speakers\\\/federico-roncarolo-canada-excellence-research-chair-cerc-one-urban-health\\\/\",\"url\":\"https:\\\/\\\/italchamber.qc.ca\\\/it\\\/speakers\\\/federico-roncarolo-canada-excellence-research-chair-cerc-one-urban-health\\\/\",\"name\":\"Federico Roncarolo \u2013 Canada Excellence Research Chair (CERC) One Urban Health - ICCC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/italchamber.qc.ca\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/italchamber.qc.ca\\\/it\\\/speakers\\\/federico-roncarolo-canada-excellence-research-chair-cerc-one-urban-health\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/italchamber.qc.ca\\\/it\\\/speakers\\\/federico-roncarolo-canada-excellence-research-chair-cerc-one-urban-health\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/italchamber.qc.ca\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Untitled-design.png\",\"datePublished\":\"2025-05-15T20:57:55+00:00\",\"dateModified\":\"2025-05-15T20:58:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/italchamber.qc.ca\\\/it\\\/speakers\\\/federico-roncarolo-canada-excellence-research-chair-cerc-one-urban-health\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/italchamber.qc.ca\\\/it\\\/speakers\\\/federico-roncarolo-canada-excellence-research-chair-cerc-one-urban-health\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/italchamber.qc.ca\\\/it\\\/speakers\\\/federico-roncarolo-canada-excellence-research-chair-cerc-one-urban-health\\\/#primaryimage\",\"url\":\"https:\\\/\\\/italchamber.qc.ca\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Untitled-design.png\",\"contentUrl\":\"https:\\\/\\\/italchamber.qc.ca\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Untitled-design.png\",\"width\":350,\"height\":350},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/italchamber.qc.ca\\\/it\\\/speakers\\\/federico-roncarolo-canada-excellence-research-chair-cerc-one-urban-health\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/italchamber.qc.ca\\\/it\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Speakers\",\"item\":\"https:\\\/\\\/italchamber.qc.ca\\\/it\\\/speakers\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Federico Roncarolo \u2013 Canada Excellence Research Chair (CERC) One Urban Health\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/italchamber.qc.ca\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/italchamber.qc.ca\\\/it\\\/\",\"name\":\"ICCC\",\"description\":\"Italian Chamber of Commerce in Canada\",\"publisher\":{\"@id\":\"https:\\\/\\\/italchamber.qc.ca\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/italchamber.qc.ca\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/italchamber.qc.ca\\\/it\\\/#organization\",\"name\":\"ICCC\",\"url\":\"https:\\\/\\\/italchamber.qc.ca\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/italchamber.qc.ca\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/italchamber.qc.ca\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/ICCC-Logo-Italian.svg\",\"contentUrl\":\"https:\\\/\\\/italchamber.qc.ca\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/ICCC-Logo-Italian.svg\",\"caption\":\"ICCC\"},\"image\":{\"@id\":\"https:\\\/\\\/italchamber.qc.ca\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Federico Roncarolo \u2013 Canada Excellence Research Chair (CERC) One Urban Health - ICCC","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/italchamber.qc.ca\/it\/speakers\/federico-roncarolo-canada-excellence-research-chair-cerc-one-urban-health\/","og_locale":"it_IT","og_type":"article","og_title":"Federico Roncarolo \u2013 Canada Excellence Research Chair (CERC) One Urban Health - ICCC","og_url":"https:\/\/italchamber.qc.ca\/it\/speakers\/federico-roncarolo-canada-excellence-research-chair-cerc-one-urban-health\/","og_site_name":"ICCC","article_modified_time":"2025-05-15T20:58:06+00:00","og_image":[{"width":350,"height":350,"url":"https:\/\/italchamber.qc.ca\/wp-content\/uploads\/2025\/05\/Untitled-design.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/italchamber.qc.ca\/it\/speakers\/federico-roncarolo-canada-excellence-research-chair-cerc-one-urban-health\/","url":"https:\/\/italchamber.qc.ca\/it\/speakers\/federico-roncarolo-canada-excellence-research-chair-cerc-one-urban-health\/","name":"Federico Roncarolo \u2013 Canada Excellence Research Chair (CERC) One Urban Health - ICCC","isPartOf":{"@id":"https:\/\/italchamber.qc.ca\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/italchamber.qc.ca\/it\/speakers\/federico-roncarolo-canada-excellence-research-chair-cerc-one-urban-health\/#primaryimage"},"image":{"@id":"https:\/\/italchamber.qc.ca\/it\/speakers\/federico-roncarolo-canada-excellence-research-chair-cerc-one-urban-health\/#primaryimage"},"thumbnailUrl":"https:\/\/italchamber.qc.ca\/wp-content\/uploads\/2025\/05\/Untitled-design.png","datePublished":"2025-05-15T20:57:55+00:00","dateModified":"2025-05-15T20:58:06+00:00","breadcrumb":{"@id":"https:\/\/italchamber.qc.ca\/it\/speakers\/federico-roncarolo-canada-excellence-research-chair-cerc-one-urban-health\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/italchamber.qc.ca\/it\/speakers\/federico-roncarolo-canada-excellence-research-chair-cerc-one-urban-health\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/italchamber.qc.ca\/it\/speakers\/federico-roncarolo-canada-excellence-research-chair-cerc-one-urban-health\/#primaryimage","url":"https:\/\/italchamber.qc.ca\/wp-content\/uploads\/2025\/05\/Untitled-design.png","contentUrl":"https:\/\/italchamber.qc.ca\/wp-content\/uploads\/2025\/05\/Untitled-design.png","width":350,"height":350},{"@type":"BreadcrumbList","@id":"https:\/\/italchamber.qc.ca\/it\/speakers\/federico-roncarolo-canada-excellence-research-chair-cerc-one-urban-health\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/italchamber.qc.ca\/it\/home\/"},{"@type":"ListItem","position":2,"name":"Speakers","item":"https:\/\/italchamber.qc.ca\/it\/speakers\/"},{"@type":"ListItem","position":3,"name":"Federico Roncarolo \u2013 Canada Excellence Research Chair (CERC) One Urban Health"}]},{"@type":"WebSite","@id":"https:\/\/italchamber.qc.ca\/it\/#website","url":"https:\/\/italchamber.qc.ca\/it\/","name":"ICCC","description":"Italian Chamber of Commerce in Canada","publisher":{"@id":"https:\/\/italchamber.qc.ca\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/italchamber.qc.ca\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/italchamber.qc.ca\/it\/#organization","name":"ICCC","url":"https:\/\/italchamber.qc.ca\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/italchamber.qc.ca\/it\/#\/schema\/logo\/image\/","url":"https:\/\/italchamber.qc.ca\/wp-content\/uploads\/2025\/05\/ICCC-Logo-Italian.svg","contentUrl":"https:\/\/italchamber.qc.ca\/wp-content\/uploads\/2025\/05\/ICCC-Logo-Italian.svg","caption":"ICCC"},"image":{"@id":"https:\/\/italchamber.qc.ca\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/italchamber.qc.ca\/it\/wp-json\/wp\/v2\/speaker\/16735","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/italchamber.qc.ca\/it\/wp-json\/wp\/v2\/speaker"}],"about":[{"href":"https:\/\/italchamber.qc.ca\/it\/wp-json\/wp\/v2\/types\/speaker"}],"version-history":[{"count":1,"href":"https:\/\/italchamber.qc.ca\/it\/wp-json\/wp\/v2\/speaker\/16735\/revisions"}],"predecessor-version":[{"id":16737,"href":"https:\/\/italchamber.qc.ca\/it\/wp-json\/wp\/v2\/speaker\/16735\/revisions\/16737"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/italchamber.qc.ca\/it\/wp-json\/wp\/v2\/media\/16731"}],"wp:attachment":[{"href":"https:\/\/italchamber.qc.ca\/it\/wp-json\/wp\/v2\/media?parent=16735"}],"wp:term":[{"taxonomy":"country","embeddable":true,"href":"https:\/\/italchamber.qc.ca\/it\/wp-json\/wp\/v2\/country?post=16735"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}