{"id":16901,"date":"2025-05-15T21:24:07","date_gmt":"2025-05-15T21:24:07","guid":{"rendered":"https:\/\/italchamber.qc.ca\/speakers\/gianluigi-riccio-meditech-competence-center\/"},"modified":"2025-05-15T21:24:19","modified_gmt":"2025-05-15T21:24:19","slug":"gianluigi-riccio-meditech-competence-center","status":"publish","type":"speaker","link":"https:\/\/italchamber.qc.ca\/fr\/speakers\/gianluigi-riccio-meditech-competence-center\/","title":{"rendered":"Gianluigi Riccio \u2013 Meditech Competence Center"},"content":{"rendered":"","protected":false},"featured_media":16898,"template":"","country":[],"class_list":["post-16901","speaker","type-speaker","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gianluigi Riccio \u2013 Meditech Competence Center - ICCC<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/italchamber.qc.ca\/fr\/speakers\/gianluigi-riccio-meditech-competence-center\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gianluigi Riccio \u2013 Meditech Competence Center - ICCC\" \/>\n<meta property=\"og:url\" content=\"https:\/\/italchamber.qc.ca\/fr\/speakers\/gianluigi-riccio-meditech-competence-center\/\" \/>\n<meta property=\"og:site_name\" content=\"ICCC\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-15T21:24:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/italchamber.qc.ca\/wp-content\/uploads\/2025\/05\/Gianluigi-Riccio-scaled-e1729691420878.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1420\" \/>\n\t<meta property=\"og:image:height\" content=\"1659\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/italchamber.qc.ca\\\/fr\\\/speakers\\\/gianluigi-riccio-meditech-competence-center\\\/\",\"url\":\"https:\\\/\\\/italchamber.qc.ca\\\/fr\\\/speakers\\\/gianluigi-riccio-meditech-competence-center\\\/\",\"name\":\"Gianluigi Riccio \u2013 Meditech Competence Center - ICCC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/italchamber.qc.ca\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/italchamber.qc.ca\\\/fr\\\/speakers\\\/gianluigi-riccio-meditech-competence-center\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/italchamber.qc.ca\\\/fr\\\/speakers\\\/gianluigi-riccio-meditech-competence-center\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/italchamber.qc.ca\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Gianluigi-Riccio-scaled-e1729691420878.jpg\",\"datePublished\":\"2025-05-15T21:24:07+00:00\",\"dateModified\":\"2025-05-15T21:24:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/italchamber.qc.ca\\\/fr\\\/speakers\\\/gianluigi-riccio-meditech-competence-center\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/italchamber.qc.ca\\\/fr\\\/speakers\\\/gianluigi-riccio-meditech-competence-center\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/italchamber.qc.ca\\\/fr\\\/speakers\\\/gianluigi-riccio-meditech-competence-center\\\/#primaryimage\",\"url\":\"https:\\\/\\\/italchamber.qc.ca\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Gianluigi-Riccio-scaled-e1729691420878.jpg\",\"contentUrl\":\"https:\\\/\\\/italchamber.qc.ca\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Gianluigi-Riccio-scaled-e1729691420878.jpg\",\"width\":1420,\"height\":1659},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/italchamber.qc.ca\\\/fr\\\/speakers\\\/gianluigi-riccio-meditech-competence-center\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/italchamber.qc.ca\\\/fr\\\/accueil\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Speakers\",\"item\":\"https:\\\/\\\/italchamber.qc.ca\\\/fr\\\/speakers\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Gianluigi Riccio \u2013 Meditech Competence Center\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/italchamber.qc.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/italchamber.qc.ca\\\/fr\\\/\",\"name\":\"ICCC\",\"description\":\"Italian Chamber of Commerce in Canada\",\"publisher\":{\"@id\":\"https:\\\/\\\/italchamber.qc.ca\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/italchamber.qc.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/italchamber.qc.ca\\\/fr\\\/#organization\",\"name\":\"ICCC\",\"url\":\"https:\\\/\\\/italchamber.qc.ca\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/italchamber.qc.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/italchamber.qc.ca\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/ICCC-Logo-French.svg\",\"contentUrl\":\"https:\\\/\\\/italchamber.qc.ca\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/ICCC-Logo-French.svg\",\"caption\":\"ICCC\"},\"image\":{\"@id\":\"https:\\\/\\\/italchamber.qc.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gianluigi Riccio \u2013 Meditech Competence Center - ICCC","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/italchamber.qc.ca\/fr\/speakers\/gianluigi-riccio-meditech-competence-center\/","og_locale":"fr_FR","og_type":"article","og_title":"Gianluigi Riccio \u2013 Meditech Competence Center - ICCC","og_url":"https:\/\/italchamber.qc.ca\/fr\/speakers\/gianluigi-riccio-meditech-competence-center\/","og_site_name":"ICCC","article_modified_time":"2025-05-15T21:24:19+00:00","og_image":[{"width":1420,"height":1659,"url":"https:\/\/italchamber.qc.ca\/wp-content\/uploads\/2025\/05\/Gianluigi-Riccio-scaled-e1729691420878.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/italchamber.qc.ca\/fr\/speakers\/gianluigi-riccio-meditech-competence-center\/","url":"https:\/\/italchamber.qc.ca\/fr\/speakers\/gianluigi-riccio-meditech-competence-center\/","name":"Gianluigi Riccio \u2013 Meditech Competence Center - ICCC","isPartOf":{"@id":"https:\/\/italchamber.qc.ca\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/italchamber.qc.ca\/fr\/speakers\/gianluigi-riccio-meditech-competence-center\/#primaryimage"},"image":{"@id":"https:\/\/italchamber.qc.ca\/fr\/speakers\/gianluigi-riccio-meditech-competence-center\/#primaryimage"},"thumbnailUrl":"https:\/\/italchamber.qc.ca\/wp-content\/uploads\/2025\/05\/Gianluigi-Riccio-scaled-e1729691420878.jpg","datePublished":"2025-05-15T21:24:07+00:00","dateModified":"2025-05-15T21:24:19+00:00","breadcrumb":{"@id":"https:\/\/italchamber.qc.ca\/fr\/speakers\/gianluigi-riccio-meditech-competence-center\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/italchamber.qc.ca\/fr\/speakers\/gianluigi-riccio-meditech-competence-center\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/italchamber.qc.ca\/fr\/speakers\/gianluigi-riccio-meditech-competence-center\/#primaryimage","url":"https:\/\/italchamber.qc.ca\/wp-content\/uploads\/2025\/05\/Gianluigi-Riccio-scaled-e1729691420878.jpg","contentUrl":"https:\/\/italchamber.qc.ca\/wp-content\/uploads\/2025\/05\/Gianluigi-Riccio-scaled-e1729691420878.jpg","width":1420,"height":1659},{"@type":"BreadcrumbList","@id":"https:\/\/italchamber.qc.ca\/fr\/speakers\/gianluigi-riccio-meditech-competence-center\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/italchamber.qc.ca\/fr\/accueil\/"},{"@type":"ListItem","position":2,"name":"Speakers","item":"https:\/\/italchamber.qc.ca\/fr\/speakers\/"},{"@type":"ListItem","position":3,"name":"Gianluigi Riccio \u2013 Meditech Competence Center"}]},{"@type":"WebSite","@id":"https:\/\/italchamber.qc.ca\/fr\/#website","url":"https:\/\/italchamber.qc.ca\/fr\/","name":"ICCC","description":"Italian Chamber of Commerce in Canada","publisher":{"@id":"https:\/\/italchamber.qc.ca\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/italchamber.qc.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/italchamber.qc.ca\/fr\/#organization","name":"ICCC","url":"https:\/\/italchamber.qc.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/italchamber.qc.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/italchamber.qc.ca\/wp-content\/uploads\/2025\/05\/ICCC-Logo-French.svg","contentUrl":"https:\/\/italchamber.qc.ca\/wp-content\/uploads\/2025\/05\/ICCC-Logo-French.svg","caption":"ICCC"},"image":{"@id":"https:\/\/italchamber.qc.ca\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/italchamber.qc.ca\/fr\/wp-json\/wp\/v2\/speaker\/16901","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/italchamber.qc.ca\/fr\/wp-json\/wp\/v2\/speaker"}],"about":[{"href":"https:\/\/italchamber.qc.ca\/fr\/wp-json\/wp\/v2\/types\/speaker"}],"version-history":[{"count":1,"href":"https:\/\/italchamber.qc.ca\/fr\/wp-json\/wp\/v2\/speaker\/16901\/revisions"}],"predecessor-version":[{"id":16903,"href":"https:\/\/italchamber.qc.ca\/fr\/wp-json\/wp\/v2\/speaker\/16901\/revisions\/16903"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/italchamber.qc.ca\/fr\/wp-json\/wp\/v2\/media\/16898"}],"wp:attachment":[{"href":"https:\/\/italchamber.qc.ca\/fr\/wp-json\/wp\/v2\/media?parent=16901"}],"wp:term":[{"taxonomy":"country","embeddable":true,"href":"https:\/\/italchamber.qc.ca\/fr\/wp-json\/wp\/v2\/country?post=16901"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}